{"id":13438,"date":"2017-12-11T15:23:43","date_gmt":"2017-12-11T19:23:43","guid":{"rendered":"http:\/\/www.mpppst.gob.ve\/mpppstweb\/?p=13438"},"modified":"2017-12-11T15:23:43","modified_gmt":"2017-12-11T19:23:43","slug":"estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017","status":"publish","type":"post","link":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/","title":{"rendered":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017"},"content":{"rendered":"<p>Minci<\/p>\n<p>Los 335 alcaldes de Venezuela fueron elegidos este domingo con una participaci\u00f3n de\u00a0<strong>9.139.564 de personas<\/strong>\u00a0que acudieron a las urnas de los 14.384 centros de votaci\u00f3n para participar en las\u00a0<strong>elecciones municipales,<\/strong>\u00a0tercer evento electoral celebrado este a\u00f1o en Venezuela.<\/p>\n<p>\u201cSon nueve millones de venezolanos los que asistieron una vez m\u00e1s a demostrar su vocaci\u00f3n democr\u00e1tica. Agradecemos a los funcionarios (del Estado) que por tercera vez y por tan poco tiempo han estado a las alturas y demandas de la poblaci\u00f3n venezolana\u201d, destac\u00f3 la vicepresidenta del Consejo Nacional Electoral (CNE),\u00a0<strong>Sandra Oblitas,<\/strong>\u00a0desde la sede de la referida instituci\u00f3n ubicada en el centro de Caracas.<\/p>\n<p>Indic\u00f3 adem\u00e1s que los m\u00e1s de nueve millones de votantes representan el<strong>\u00a047.32 % del padr\u00f3n de votantes<\/strong>, que supera los 19 millones; mientras que los resultados fueron emitidos con la\u00a0<strong>transmisi\u00f3n de 31.800 m\u00e1quinas<\/strong>\u00a0de votaci\u00f3n de las 32.700 que fueron habilitadas.<\/p>\n<h4>#ElChavismoArras\u00f3 en las alcald\u00edas<\/h4>\n<p>En estas elecciones,\u00a0<strong>la Revoluci\u00f3n Bolivariana se impuso en los municipios capitales,<\/strong>conquistando 23.<\/p>\n<p>\u201cFue una jornada de participaci\u00f3n y de demostraci\u00f3n del pueblo venezolano y de su convicci\u00f3n de su vocaci\u00f3n democr\u00e1ticas, de su convicci\u00f3n de paz y de que justamente son los procesos electorales un espacio de participaci\u00f3n confiable y seguro\u201d, manifest\u00f3 Oblitas antes de dar a conocer el primer bolet\u00edn.<\/p>\n<p>&nbsp;<\/p>\n<p>Con los resultados emitidos hasta el momento, las<strong>\u00a0juntas electorales<\/strong>\u00a0\u2014declar\u00f3\u2014 \u201cquedan autorizadas para seguir con la t<strong>otalizaci\u00f3n de los datos<\/strong>\u00a0en sus municipios\u201d.<\/p>\n<h4>Primer bolet\u00edn del CNE<\/h4>\n<p>A continuaci\u00f3n, conozca el listado correspondiente al primer bolet\u00edn de resultados de las elecciones municipales 2017, emitido por el\u00a0CNE\u00a0la noche de este domingo.<\/p>\n<p><strong>Distrito Capital<\/strong><\/p>\n<p>Municipio Libertador: Erika Far\u00edas (PSUV) con 491.328 votos, lo que representa el 66,17% del padr\u00f3n de electores.<\/p>\n<p><strong>Anzo\u00e1tegui<\/strong><\/p>\n<p>Sim\u00f3n Bol\u00edvar (capital de estado): Luis Jos\u00e9 Marcano (PSUV) 82.609 votos para un 59%.<\/p>\n<p>Sotillo: Herminia Garc\u00eda (PSUV) con 46.775 votos para un 55.51%.<\/p>\n<p><strong>Amazonas<\/strong><\/p>\n<p>Atures (capital de estado): Jos\u00e9 Zamora (PSUV) 24.000 votos que representa 91.18%.<\/p>\n<p><strong>Aragua<\/strong><\/p>\n<p>Girardot (capital de estado): Pedro Bastidas (PSUV) con 99.259 de los votos, lo que representa 65.69% de los sufragios.<\/p>\n<p>Santiago Mari\u00f1o: Yohana S\u00e1nchez (PSUV) 40.986 de los votos, lo que representa 66.199% de los sufragios emitidos.<\/p>\n<p><strong>Apure<\/strong><\/p>\n<p>San Fernando (capital de estado): Ofelia Padr\u00f3n (PSUV) con 37.751 de los votos, lo que representa 76.78% de los sufragios emitidos.<\/p>\n<p><strong>Barinas<\/strong><\/p>\n<p>Antonio Jos\u00e9 de Sucre: Belkys Biriachi (PSUV) con 11.852 votos, lo que representa 62.44%<\/p>\n<p>Barinas (capital de estado): Nancy P\u00e9rez (PSUV) con 52.024 votos que representa 65.53%.<\/p>\n<p><strong>Bol\u00edvar<\/strong><\/p>\n<p>Caron\u00ed: Tito Oviedo (PSUV) con 113.053 votos, que representa del 68,22%.<\/p>\n<p>Heres (Capital de estado): Sergio Hern\u00e1ndez (PSUV) con 51.356 votos, equivalente al 63,05%.<\/p>\n<p><strong>Carabobo<\/strong><\/p>\n<p>Puerto Cabello: Juan Carlos Betancourt (PSUV) con 48.191 votos para un 70,56%.<\/p>\n<p>Valencia (capital de estado): Jes\u00fas Alejandro M\u00e1rvez (PSUV) con 161.087 votos, equivalente al 70,36%.<\/p>\n<p><strong>Cojedes<\/strong><\/p>\n<p>Ezequiel Zamora (capital de estado): Rafael Alem\u00e1n (PSUV) con 28.519 votos, equivalente al 68,42%.<\/p>\n<p>Tinaquillo: Luis Yoyotte (PSUV) con 23mil 383 votos para un 86.57%<\/p>\n<p><strong>Delta Amacuro<\/strong><\/p>\n<p>Casacoima: Edgar Guzm\u00e1n (PSUV) con 6.134 votos para un 53.74%.<\/p>\n<p>Tucupita (capital de estado): Loa Tamaroni (PSUV) con 27.496 votos, el 63,96% de los votos emitidos.<\/p>\n<p><strong>Falc\u00f3n<\/strong><\/p>\n<p>Carirubana: Alcides Goitia (PSUV) m\u00e1s de 51.030 votos, lo que representa el 69.16%.<\/p>\n<p>Miranda (capital de estado): Pablo Acosta (PSUV) con 35.833 electores para un 50,33%.<\/p>\n<p><strong>Gu\u00e1rico<\/strong><\/p>\n<p>Francisco de Miranda: Francisco Graterol (PSUV) con 29.513 votos para 73.45%<\/p>\n<p>Juan Germ\u00e1n Roscio (capital de estado): Mayerling Colmenares (PSUV) con 30.733 votos para un 63.32%.<\/p>\n<p><strong>Lara<\/strong><\/p>\n<p>Iribarren (capital de estado): Luis Jon\u00e1s Reyes (PSUV) con 199.981 votos para un 71,08%.<\/p>\n<p>Torres: Edgar Carrasco (PSUV) con 42.819 votos para un 80.03%.<\/p>\n<p><strong>M\u00e9rida<\/strong><\/p>\n<p>Alberto Adriani: Mezin Abou Assi (PSUV) con 25.418 votos para un 54.52%.<\/p>\n<p><strong>Miranda<\/strong><\/p>\n<p>Carrizal: Farith Fraija (PSUV) con 10.636 votos.<\/p>\n<p>Guaicaipuro (capital de estado): Wisely \u00c1lvarez (PSUV) 57.282 votos para un 69,42%.<\/p>\n<p>Sucre: Jos\u00e9 Vicente Rangel \u00c1valos (PSUV)<\/p>\n<p><strong>Monagas<\/strong><\/p>\n<p>Ezequiel Zamora: Raul Brazon (PSUV) con 13.103 votos para un 61.19%.<\/p>\n<p>Matur\u00edn (capital de estado): Wilfredo Ordaz (PSUV) con 116.458 votos para un 75%.<\/p>\n<p><strong>Nueva Esparta<\/strong><\/p>\n<p>Mari\u00f1o: Francisco Gonz\u00e1lez (PSUV) con 22.802 votos para un 54.44%.<\/p>\n<p><strong>Portuguesa<\/strong><\/p>\n<p>Guanare (capital de estado): \u00d3scar Novoa (PSUV) con 47.008 votos para un 82.04%.<\/p>\n<p>P\u00e1ez: Efr\u00e9n P\u00e9rez (PSUV) con 43.874 votos para un 87,75% de los votos emitidos.<\/p>\n<p>Zamora: Ra\u00fal Braz\u00f3n (PSUV) con 13.103 votos, que representa 71,19 % de los sufragios emitidos.<\/p>\n<p><strong>Sucre<\/strong><\/p>\n<p>Berm\u00fadez: Nircia Villegas (PSUV) con 30.865 votos, lo que significa el 63.18% del sufragio.<\/p>\n<p>Sucre (capital de estado): Luis Sifontes (PSUV) con 71.75% al obtener 80.404 votos.<\/p>\n<p><strong>T\u00e1chira<\/strong><\/p>\n<p>San Crist\u00f3bal (capital de estado): Gustavo Delgado (Copei) con el 53,78% de los votos, lo que representa la voluntad de 47.142 electores.<\/p>\n<p><strong>Trujillo<\/strong><\/p>\n<p>Trujillo (capital de estado): Angerson Hern\u00e1ndez (PSUV) con 18. 053 votos para un 82.02%.<\/p>\n<p>Valera: Iroshima V\u00e1squez (PSUV) con 34.759 votos, es decir el 80.66% del sufragio.<\/p>\n<p><strong>Vargas<\/strong><\/p>\n<p>Vargas: Jos\u00e9 Alejandro Ter\u00e1n (PSUV) con 105.146 votos para un 85.57%.<\/p>\n<p><strong>Yaracuy<\/strong><\/p>\n<p>Pe\u00f1a: Juan Parada (PSUV) con un total de 26.314 votos para 81,31%.<\/p>\n<p>San Felipe (capital de estado): Carlos Gamarra (PSUV) con 28.112 votos para un 78.56%<\/p>\n<p><strong>Zulia<\/strong><\/p>\n<p>Gobernaci\u00f3n del estado Zulia: Omar Prieto (PSUV) 694.896 votos para 57,3%.<\/p>\n<p>Maracaibo (capital de estado): Willy Casanova (PSUV) 224.808 votos para 50,38%.<\/p>\n<p>San Francisco: Dirwings Arrieta (PSUV) 86.127 votos para un porcentaje de 58,51%.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minci Los 335 alcaldes de Venezuela fueron elegidos este domingo con una participaci\u00f3n de\u00a09.139.564 de personas\u00a0que &hellip; <a title=\"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017\" class=\"hm-read-more\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\"><span class=\"screen-reader-text\">Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017<\/span>Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":13439,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST\" \/>\n<meta property=\"og:description\" content=\"Minci Los 335 alcaldes de Venezuela fueron elegidos este domingo con una participaci\u00f3n de\u00a09.139.564 de personas\u00a0que &hellip; Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017Read more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"MPPPST\" \/>\n<meta property=\"article:published_time\" content=\"2017-12-11T19:23:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MPPPST Prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MPPPST Prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\"},\"author\":{\"name\":\"MPPPST Prensa\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\"},\"headline\":\"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017\",\"datePublished\":\"2017-12-11T19:23:43+00:00\",\"dateModified\":\"2017-12-11T19:23:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\"},\"wordCount\":855,\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg\",\"articleSection\":[\"Gobierno Nacional\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\",\"name\":\"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg\",\"datePublished\":\"2017-12-11T19:23:43+00:00\",\"dateModified\":\"2017-12-11T19:23:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"name\":\"MPPPST\",\"description\":\"Ministerio del Poder Popular para el Proceso Social de Trabajo\",\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\",\"name\":\"mpppst\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"width\":1080,\"height\":241,\"caption\":\"mpppst\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\",\"name\":\"MPPPST Prensa\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/","og_locale":"es_ES","og_type":"article","og_title":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST","og_description":"Minci Los 335 alcaldes de Venezuela fueron elegidos este domingo con una participaci\u00f3n de\u00a09.139.564 de personas\u00a0que &hellip; Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017Read more","og_url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/","og_site_name":"MPPPST","article_published_time":"2017-12-11T19:23:43+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg","type":"image\/jpeg"}],"author":"MPPPST Prensa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MPPPST Prensa","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#article","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/"},"author":{"name":"MPPPST Prensa","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4"},"headline":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017","datePublished":"2017-12-11T19:23:43+00:00","dateModified":"2017-12-11T19:23:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/"},"wordCount":855,"publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg","articleSection":["Gobierno Nacional","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/","name":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017 - MPPPST","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg","datePublished":"2017-12-11T19:23:43+00:00","dateModified":"2017-12-11T19:23:43+00:00","breadcrumb":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#primaryimage","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2017\/12\/eleciones_municipales81512960137.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2017\/12\/11\/estos-son-los-resultados-del-primer-boletin-de-las-elecciones-municipales-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/"},{"@type":"ListItem","position":2,"name":"Estos son los resultados del primer bolet\u00edn de las elecciones municipales 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","name":"MPPPST","description":"Ministerio del Poder Popular para el Proceso Social de Trabajo","publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization","name":"mpppst","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","width":1080,"height":241,"caption":"mpppst"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4","name":"MPPPST Prensa","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/13438"}],"collection":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/comments?post=13438"}],"version-history":[{"count":1,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/13438\/revisions"}],"predecessor-version":[{"id":13440,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/13438\/revisions\/13440"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media\/13439"}],"wp:attachment":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media?parent=13438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/categories?post=13438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/tags?post=13438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}