{"id":14445,"date":"2018-04-30T10:39:44","date_gmt":"2018-04-30T14:39:44","guid":{"rendered":"http:\/\/www.mpppst.gob.ve\/mpppstweb\/?p=14445"},"modified":"2018-04-30T14:15:51","modified_gmt":"2018-04-30T18:15:51","slug":"conozca-la-historia-del-1ero-de-mayo","status":"publish","type":"post","link":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/","title":{"rendered":"Conozca la Historia del 1ero de mayo"},"content":{"rendered":"<p>Marbelys Mav\u00e1rez Laguna<\/p>\n<p>(Caracas, 30 de abril de 2018) La historia del 1ero de mayo tiene mucha tela que cortar. No obstante, si hay algo cierto es que el 1ero de mayo es una manifestaci\u00f3n de la clase obrera en contra del capitalismo y de la explotaci\u00f3n que le es inherente. Es lo primero que se debe decir. Pero hay m\u00e1s. El 1ero de mayo fue una sublevaci\u00f3n de los trabajadores por lograr reivindicaciones laborales. Eso es cierto. Pero la lucha trascendi\u00f3 este hecho, pues la clase obrera del siglo XVIII se pronunci\u00f3 a favor de la libertad, de la no opresi\u00f3n y de un modelo que considerara a hombres y mujeres como sujetos sociales.<\/p>\n<p><strong>La explotaci\u00f3n del hombre<\/strong><\/p>\n<p>Pues bien, el 1ero de mayo de 1886 la Uni\u00f3n Central Obrera de Chicago, adherida a la Asociaci\u00f3n internacional de los Trabajadores (AIT) de tendencia anarquista, declar\u00f3 la huelga que paraliz\u00f3 cerca de 12 mil f\u00e1bricas en los EEUU. Este dato es revelador. Imaginemos 12 mil f\u00e1bricas en 1886. Probablemente gran parte del pa\u00eds paralizado. \u00bfPor qu\u00e9 esta manifestaci\u00f3n? La respuesta es sencilla: los trabajadores y trabajadoras luchaban por la reducci\u00f3n de la jornada laboral a 8 horas y por dignas condiciones de trabajo. Pero especialmente luchaban por ser libres, pues el modelo los hab\u00eda vuelto esclavos. \u00a0Es la \u00fanica opci\u00f3n que ofrece el capitalismo.<\/p>\n<p>De acuerdo con el historiador Federico Villalba Frontano, el meollo en este modelo se encuentra en el tiempo de trabajo que nos sustraen y no es pagado. Es la llamada plusval\u00eda o plusvalor, del cual se apropia el due\u00f1o de los medios de producci\u00f3n o capitalista.<\/p>\n<p>Otro dato no menos importante: en Detroit 11 mil trabajadores marcharon en un desfile de ocho horas. Nueva York se levant\u00f3 con una marcha de 25 mil obreros con antorchas en manos. En Chicago, la huelga par\u00f3 casi completamente la ciudad.<\/p>\n<p>Los d\u00edas siguientes se realizaron concentraciones por los 2 mil 100 obreros despedidos de la f\u00e1brica Mc Cormicks. Fueron despedidos e inmediatamente sustituidos por otros 2 mil 100. Una forma que usa el sistema capitalista de producci\u00f3n para demostrar su poder.<\/p>\n<p>No obstante, la clase obrera estaba decidida en <em>\u201ctomar el cielo por asalto\u201d<\/em>, en virtud de que se trat\u00f3 de una verdadera Revoluci\u00f3n de la clase obrera. Y mientras August Spies (uno de los m\u00e1rtires) daba su discurso, un centenar de obreros se acerc\u00f3 hasta \u00a0la f\u00e1brica Mc Cormicks para hacer un llamado a la \u00a0solidaridad con el resto de los compa\u00f1eros. La polic\u00eda arremeti\u00f3 contra la multitud, dejando seis muertos y muchos heridos m\u00e1s.<\/p>\n<p><strong>M\u00e1rtires de siempre <\/strong><\/p>\n<p>Spies y sus compa\u00f1eros llamaron a una manifestaci\u00f3n para el d\u00eda siguiente en la plaza Haymarket. Miles de personas se concentraron all\u00ed. Los anarquistas toman la palabra, transcurriendo as\u00ed la noche. Fielden terminaba su discurso cuando la polic\u00eda ordena disolver el mitin. Se produjo un estruendo: cayeron al suelo m\u00e1s de sesenta polic\u00edas heridos y un muerto. La represi\u00f3n se desata sobre toda la ciudad. Son detenidos ocho anarquistas. August Spies, Michael Schwab, Adolph Fischer, George Engel, Louis Lingg, Albert Parsons, Samuel Fielden y Oscar Neebe fueron sometidos a juicio.<\/p>\n<p>La pregunta que sobreviene es \u00bfpor qu\u00e9 los trabajadores decidieron parar un pa\u00eds y con ello crear un precedente, o m\u00e1s a\u00fan: lograr la libertad definitiva? La respuesta es sencilla: el capitalismo hab\u00eda generado una gran riqueza a costa de los trabajadores. Les hab\u00eda arrebatado el tiempo, su energ\u00eda, pero no la conciencia. As\u00ed, se debe se\u00f1alar que en Inglaterra hab\u00eda jornadas laborales de 16 horas. En este mismo pa\u00eds un obrero ganaba 600 libras esterlinas; un profesional ganaba 1000, mientras los grandes se\u00f1ores ganaban 50 mil. Como puede observarse, una gran brecha en la estructura de clases. \u00a0El salario de un trabajador siempre ha sido el suficiente para la reproducci\u00f3n de su fuerza de trabajo. \u201cNo se puede ganar m\u00e1s de la subsistencia\u201d, tal como lo deja claro Villalba Frontano.<\/p>\n<p><strong>La ejecuci\u00f3n narrada \u00a0por Jos\u00e9 Mart\u00ed<\/strong><\/p>\n<p>(&#8230;) \u00absalen de sus celdas. Se dan la mano, sonr\u00eden. Les leen la sentencia, les sujetan las manos por la espalda con esposas, les ci\u00f1en los brazos al cuerpo con una faja de cuero y les ponen una mortaja blanca como la t\u00fanica de los catec\u00famenos cristianos. Abajo est\u00e1 la concurrencia, sentada en hilera de sillas delante del cadalso como en un teatro&#8230; Firmeza en el rostro de Fischer, plegaria en el de Spies, orgullo en el del Parsons, Engel hace un chiste a prop\u00f3sito de su capucha, Spies grita: \u00abla voz que vais a sofocar ser\u00e1 m\u00e1s poderosa en el futuro que cuantas palabras pudiera yo decir ahora\u00bb. Les bajan las capuchas, luego una se\u00f1a, un ruido, la trampa cede, los cuatro cuerpos caen y se balancean en una danza espantable&#8230;\u00bb. De esta forma fue narrada <strong>la \u00a0ejecuci\u00f3n \u00a0por Jos\u00e9 Mart\u00ed, corresponsal en Chicago del diario La Naci\u00f3n<\/strong>. Por cierto, la culpabilidad de los condenados nunca fue probada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marbelys Mav\u00e1rez Laguna (Caracas, 30 de abril de 2018) La historia del 1ero de mayo tiene &hellip; <a title=\"Conozca la Historia del 1ero de mayo\" class=\"hm-read-more\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\"><span class=\"screen-reader-text\">Conozca la Historia del 1ero de mayo<\/span>Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":14447,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,83,163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Conozca la Historia del 1ero de mayo - MPPPST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conozca la Historia del 1ero de mayo - MPPPST\" \/>\n<meta property=\"og:description\" content=\"Marbelys Mav\u00e1rez Laguna (Caracas, 30 de abril de 2018) La historia del 1ero de mayo tiene &hellip; Conozca la Historia del 1ero de mayoRead more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\" \/>\n<meta property=\"og:site_name\" content=\"MPPPST\" \/>\n<meta property=\"article:published_time\" content=\"2018-04-30T14:39:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-04-30T18:15:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"269\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MPPPST Prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MPPPST Prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\"},\"author\":{\"name\":\"MPPPST Prensa\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\"},\"headline\":\"Conozca la Historia del 1ero de mayo\",\"datePublished\":\"2018-04-30T14:39:44+00:00\",\"dateModified\":\"2018-04-30T18:15:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\"},\"wordCount\":863,\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg\",\"articleSection\":[\"Gobierno Nacional\",\"Ministerio\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\",\"name\":\"Conozca la Historia del 1ero de mayo - MPPPST\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg\",\"datePublished\":\"2018-04-30T14:39:44+00:00\",\"dateModified\":\"2018-04-30T18:15:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg\",\"width\":600,\"height\":269},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Conozca la Historia del 1ero de mayo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"name\":\"MPPPST\",\"description\":\"Ministerio del Poder Popular para el Proceso Social de Trabajo\",\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\",\"name\":\"mpppst\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"width\":1080,\"height\":241,\"caption\":\"mpppst\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\",\"name\":\"MPPPST Prensa\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Conozca la Historia del 1ero de mayo - MPPPST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/","og_locale":"es_ES","og_type":"article","og_title":"Conozca la Historia del 1ero de mayo - MPPPST","og_description":"Marbelys Mav\u00e1rez Laguna (Caracas, 30 de abril de 2018) La historia del 1ero de mayo tiene &hellip; Conozca la Historia del 1ero de mayoRead more","og_url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/","og_site_name":"MPPPST","article_published_time":"2018-04-30T14:39:44+00:00","article_modified_time":"2018-04-30T18:15:51+00:00","og_image":[{"width":600,"height":269,"url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg","type":"image\/jpeg"}],"author":"MPPPST Prensa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MPPPST Prensa","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#article","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/"},"author":{"name":"MPPPST Prensa","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4"},"headline":"Conozca la Historia del 1ero de mayo","datePublished":"2018-04-30T14:39:44+00:00","dateModified":"2018-04-30T18:15:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/"},"wordCount":863,"publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg","articleSection":["Gobierno Nacional","Ministerio","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/","name":"Conozca la Historia del 1ero de mayo - MPPPST","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg","datePublished":"2018-04-30T14:39:44+00:00","dateModified":"2018-04-30T18:15:51+00:00","breadcrumb":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#primaryimage","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/04\/1-de-mayo.jpg","width":600,"height":269},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/04\/30\/conozca-la-historia-del-1ero-de-mayo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/"},{"@type":"ListItem","position":2,"name":"Conozca la Historia del 1ero de mayo"}]},{"@type":"WebSite","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","name":"MPPPST","description":"Ministerio del Poder Popular para el Proceso Social de Trabajo","publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization","name":"mpppst","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","width":1080,"height":241,"caption":"mpppst"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4","name":"MPPPST Prensa","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14445"}],"collection":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/comments?post=14445"}],"version-history":[{"count":1,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14445\/revisions"}],"predecessor-version":[{"id":14448,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14445\/revisions\/14448"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media\/14447"}],"wp:attachment":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media?parent=14445"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/categories?post=14445"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/tags?post=14445"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}