{"id":14459,"date":"2018-05-01T05:46:59","date_gmt":"2018-05-01T09:46:59","guid":{"rendered":"http:\/\/www.mpppst.gob.ve\/mpppstweb\/?p=14459"},"modified":"2018-05-01T05:47:20","modified_gmt":"2018-05-01T09:47:20","slug":"presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil","status":"publish","type":"post","link":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/","title":{"rendered":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil"},"content":{"rendered":"<p>AVN. (30 de abril de 2018).\u00a0El presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, anunci\u00f3 este lunes el Bono de la Clase Obrera, que se entregar\u00e1 a partir de este 1\u00ba de mayo, D\u00eda Internacional del Trabajador, por un monto de 1 mill\u00f3n 500 mil bol\u00edvares para un total de 10 millones de venezolanos, a trav\u00e9s del Carnet de la Patria.<\/p>\n<p>En una rueda de prensa transmitida por VTV, indic\u00f3 que la entrega del bono se realizar\u00e1 a trav\u00e9s del sistema veQR \u00aben apoyo \u00fanico y especial a la clase obrera del pa\u00eds\u00bb.<\/p>\n<p>En conmemoraci\u00f3n del D\u00eda Internacional del Trabajador llam\u00f3 a la clase obrera y trabajadora, en compa\u00f1\u00eda de la militancia revolucionaria, a una movilizaci\u00f3n este martes, en las calles de Caracas.<\/p>\n<p>\u00abMa\u00f1ana los convoco a la calle, a la lucha, a la batalla. Ma\u00f1ana habr\u00e1 una gran movilizaci\u00f3n en varios lugares del pa\u00eds, en Caracas es la gran movilizaci\u00f3n nacional, va a estar descomunal, los invito a la gran movilizaci\u00f3n de la clase obrera con la consigna: \u00a1Pa&#8217; lante es pa&#8217; all\u00e1!\u00bb, expres\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>AVN. (30 de abril de 2018).\u00a0El presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, anunci\u00f3 este lunes el &hellip; <a title=\"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil\" class=\"hm-read-more\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\"><span class=\"screen-reader-text\">Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil<\/span>Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":14460,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST\" \/>\n<meta property=\"og:description\" content=\"AVN. (30 de abril de 2018).\u00a0El presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, anunci\u00f3 este lunes el &hellip; Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 milRead more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\" \/>\n<meta property=\"og:site_name\" content=\"MPPPST\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-01T09:46:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-01T09:47:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"401\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MPPPST Prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MPPPST Prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\"},\"author\":{\"name\":\"MPPPST Prensa\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\"},\"headline\":\"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil\",\"datePublished\":\"2018-05-01T09:46:59+00:00\",\"dateModified\":\"2018-05-01T09:47:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\"},\"wordCount\":199,\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg\",\"articleSection\":[\"Gobierno Nacional\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\",\"name\":\"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg\",\"datePublished\":\"2018-05-01T09:46:59+00:00\",\"dateModified\":\"2018-05-01T09:47:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg\",\"width\":750,\"height\":401},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"name\":\"MPPPST\",\"description\":\"Ministerio del Poder Popular para el Proceso Social de Trabajo\",\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\",\"name\":\"mpppst\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"width\":1080,\"height\":241,\"caption\":\"mpppst\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\",\"name\":\"MPPPST Prensa\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST","og_description":"AVN. (30 de abril de 2018).\u00a0El presidente de la Rep\u00fablica, Nicol\u00e1s Maduro, anunci\u00f3 este lunes el &hellip; Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 milRead more","og_url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/","og_site_name":"MPPPST","article_published_time":"2018-05-01T09:46:59+00:00","article_modified_time":"2018-05-01T09:47:20+00:00","og_image":[{"width":750,"height":401,"url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg","type":"image\/jpeg"}],"author":"MPPPST Prensa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MPPPST Prensa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#article","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/"},"author":{"name":"MPPPST Prensa","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4"},"headline":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil","datePublished":"2018-05-01T09:46:59+00:00","dateModified":"2018-05-01T09:47:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/"},"wordCount":199,"publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg","articleSection":["Gobierno Nacional","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/","name":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil - MPPPST","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg","datePublished":"2018-05-01T09:46:59+00:00","dateModified":"2018-05-01T09:47:20+00:00","breadcrumb":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#primaryimage","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/bono-trabajador.jpg","width":750,"height":401},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/01\/presidente-maduro-anuncia-bono-de-la-clase-obrera-de-bs-1-millon-500-mil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/"},{"@type":"ListItem","position":2,"name":"Presidente Maduro anuncia Bono de la Clase Obrera de Bs. 1 mill\u00f3n 500 mil"}]},{"@type":"WebSite","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","name":"MPPPST","description":"Ministerio del Poder Popular para el Proceso Social de Trabajo","publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization","name":"mpppst","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","width":1080,"height":241,"caption":"mpppst"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4","name":"MPPPST Prensa","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14459"}],"collection":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/comments?post=14459"}],"version-history":[{"count":1,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14459\/revisions"}],"predecessor-version":[{"id":14461,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14459\/revisions\/14461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media\/14460"}],"wp:attachment":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media?parent=14459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/categories?post=14459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/tags?post=14459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}