{"id":14644,"date":"2018-05-31T09:34:00","date_gmt":"2018-05-31T13:34:00","guid":{"rendered":"http:\/\/www.mpppst.gob.ve\/mpppstweb\/?p=14644"},"modified":"2018-05-31T09:34:00","modified_gmt":"2018-05-31T13:34:00","slug":"presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba","status":"publish","type":"post","link":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/","title":{"rendered":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba"},"content":{"rendered":"<p>Minci<\/p>\n<p>El presidente de la Rep\u00fablica Bolivariana de Venezuela, Nicol\u00e1s Maduro, consolid\u00f3 y renov\u00f3 los proyectos de las misiones, y grandes misiones y recursos energ\u00e9ticos donde participan ambos pa\u00edses.<\/p>\n<p>Esta informaci\u00f3n la ofreci\u00f3 durante una reuni\u00f3n con el presidente de los Consejos de Estados y de Ministros de la Rep\u00fablica de Cuba, Miguel Mario D\u00edaz Canel Berm\u00fadez.<\/p>\n<p>Inform\u00f3 que con esta visita tomar\u00e1 dos l\u00edneas de acci\u00f3n; la primera fortalecer\u00e1 las l\u00edneas de trabajo para mejorar Misi\u00f3n Barrio Adentro, Misi\u00f3n Cultura Coraz\u00f3n Adentro, misiones deportivas, Misi\u00f3n Milagro y consolidar las corporaciones energ\u00e9ticas, econ\u00f3micas, comerciales y tur\u00edsticas.<\/p>\n<p>Igualmente, la segunda l\u00ednea ser\u00e1 de acciones, de los nuevos proyectos industriales, agr\u00edcolas, mineros y tur\u00edsticos.<\/p>\n<p>\u201cTenemos la voluntad para que juntos avancemos en nuevos proyectos de creaci\u00f3n de riquezas, de fuerzas productivas\u201d, dijo El Presidente.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Minci El presidente de la Rep\u00fablica Bolivariana de Venezuela, Nicol\u00e1s Maduro, consolid\u00f3 y renov\u00f3 los proyectos &hellip; <a title=\"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba\" class=\"hm-read-more\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\"><span class=\"screen-reader-text\">Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba<\/span>Read more<\/a><\/p>\n","protected":false},"author":25,"featured_media":14645,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[82,163],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST\" \/>\n<meta property=\"og:description\" content=\"Minci El presidente de la Rep\u00fablica Bolivariana de Venezuela, Nicol\u00e1s Maduro, consolid\u00f3 y renov\u00f3 los proyectos &hellip; Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con CubaRead more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\" \/>\n<meta property=\"og:site_name\" content=\"MPPPST\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-31T13:34:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"MPPPST Prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MPPPST Prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\"},\"author\":{\"name\":\"MPPPST Prensa\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\"},\"headline\":\"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba\",\"datePublished\":\"2018-05-31T13:34:00+00:00\",\"dateModified\":\"2018-05-31T13:34:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\"},\"wordCount\":173,\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg\",\"articleSection\":[\"Gobierno Nacional\",\"Noticias\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\",\"name\":\"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg\",\"datePublished\":\"2018-05-31T13:34:00+00:00\",\"dateModified\":\"2018-05-31T13:34:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"name\":\"MPPPST\",\"description\":\"Ministerio del Poder Popular para el Proceso Social de Trabajo\",\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\",\"name\":\"mpppst\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"width\":1080,\"height\":241,\"caption\":\"mpppst\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\",\"name\":\"MPPPST Prensa\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/","og_locale":"es_ES","og_type":"article","og_title":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST","og_description":"Minci El presidente de la Rep\u00fablica Bolivariana de Venezuela, Nicol\u00e1s Maduro, consolid\u00f3 y renov\u00f3 los proyectos &hellip; Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con CubaRead more","og_url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/","og_site_name":"MPPPST","article_published_time":"2018-05-31T13:34:00+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg","type":"image\/jpeg"}],"author":"MPPPST Prensa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MPPPST Prensa","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#article","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/"},"author":{"name":"MPPPST Prensa","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4"},"headline":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba","datePublished":"2018-05-31T13:34:00+00:00","dateModified":"2018-05-31T13:34:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/"},"wordCount":173,"publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg","articleSection":["Gobierno Nacional","Noticias"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/","name":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba - MPPPST","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage"},"thumbnailUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg","datePublished":"2018-05-31T13:34:00+00:00","dateModified":"2018-05-31T13:34:00+00:00","breadcrumb":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#primaryimage","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2018\/05\/013_JZ7800_P.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2018\/05\/31\/presidente-maduro-consolido-la-renovacion-de-los-proyectos-de-las-misiones-y-recursos-energeticos-con-cuba\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/"},{"@type":"ListItem","position":2,"name":"Presidente Maduro consolid\u00f3 la renovaci\u00f3n de los proyectos de las misiones y recursos energ\u00e9ticos con Cuba"}]},{"@type":"WebSite","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","name":"MPPPST","description":"Ministerio del Poder Popular para el Proceso Social de Trabajo","publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization","name":"mpppst","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","width":1080,"height":241,"caption":"mpppst"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4","name":"MPPPST Prensa","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14644"}],"collection":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/comments?post=14644"}],"version-history":[{"count":1,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14644\/revisions"}],"predecessor-version":[{"id":14646,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/14644\/revisions\/14646"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media\/14645"}],"wp:attachment":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media?parent=14644"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/categories?post=14644"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/tags?post=14644"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}