{"id":2602,"date":"2015-03-11T19:20:37","date_gmt":"2015-03-11T19:20:37","guid":{"rendered":"http:\/\/www.mpppst.gob.ve\/mpppstweb\/?p=2602"},"modified":"2016-07-01T14:45:28","modified_gmt":"2016-07-01T14:45:28","slug":"la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais","status":"publish","type":"post","link":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/","title":{"rendered":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds"},"content":{"rendered":"<p style=\"text-align: justify;\">La clase obrera que est\u00e1 en los medios de producci\u00f3n est\u00e1 llamada a asumir el control y producci\u00f3n en las empresas del pa\u00eds, y a distribuir equitativamente la riqueza, en estos momentos que Venezuela est\u00e1 a las puertas de la transici\u00f3n al socialismo.<\/p>\n<p style=\"text-align: justify;\">As\u00ed lo expres\u00f3 el viceministro para Educaci\u00f3n y el Trabajo para la Liberaci\u00f3n, Luis Rodr\u00edguez, durante el conversatorio \u201cLa Clase Obrera, vanguardia socialista\u201d, quien a\u00f1adi\u00f3 que el imperialismo ha ido perdiendo poder con el paso del tiempo, pasando por tres momentos claves en la crisis del Capitalismo: el primero cuando Richard Nixon desvinculaba al d\u00f3lar del patr\u00f3n oro.<\/p>\n<p style=\"text-align: justify;\">En segundo lugar, la derrota de Estados Unidos en la Guerra de Vietnan o victoria de los otros ante el Imperialismo, y finalmente el proceso de nacionalizaci\u00f3n de hidrocarburos en diferentes pa\u00edses. \u201cEs por ello que el imperio ha ido perdiendo espacio frente a los medios de producci\u00f3n, y la clase obrera debe consolidarse y ponerse al frente de la misma\u201d, acot\u00f3.<\/p>\n<p style=\"text-align: justify;\">Por su parte, Miguel Aponte, trabajador de Aceite Diana, sede Carabobo, explic\u00f3 que en esa empresa se ha ido elevando los niveles de conciencia de los trabajadores y trabajadoras de la industria, porque no solamente se enfocan en lo que producen sino que tambi\u00e9n pertenecen a las UBCH, PSUV; Milicias obreras, entre otros.<\/p>\n<p style=\"text-align: justify;\">Record\u00f3 que son m\u00e1s de 2500 trabajadores y trabajadoras a nivel nacional que producen soberan\u00eda alimentaria para el pueblo y que poco a poco se han ido empoderando del proceso productivo.<\/p>\n<p style=\"text-align: justify;\">Jos\u00e9 Guerra, trabajador de Calderys Refractarios del estado Bol\u00edvar, durante su intervenci\u00f3n cont\u00f3 c\u00f3mo los trabajadores empezaron a levantar la empresa, luego que sus due\u00f1os abandonaran el pa\u00eds.<\/p>\n<p style=\"text-align: justify;\">Explic\u00f3 que la clave para esta recuperaci\u00f3n progresiva de la empresa ha sido la capacitaci\u00f3n y organizaci\u00f3n de la clase trabajadora, siguiendo el legado que dej\u00f3 el Comandante Hugo Ch\u00e1vez de crear conciencia para ver los resultados positivos a corto plazo.<\/p>\n<p style=\"text-align: justify;\">Finalmente, Wilfredo Jim\u00e9nez, productor del campo en San Juan de los Morros, explic\u00f3 que su intervenci\u00f3n no es sobre una empresa recuperada sino de una empresa que se est\u00e1 constituyendo en empresa de producci\u00f3n social.<\/p>\n<p style=\"text-align: justify;\">Destac\u00f3 la importancia de que la clase obrera se incorpore a las luchas, tanto en las f\u00e1bricas como en las comunidades, y record\u00f3 que el camino a seguir es la propiedad social que nos llevar\u00e1 al benefici\u00f3 del poder.<\/p>\n<p style=\"text-align: justify;\">Este conversatorio est\u00e1 enmarcado en las actividades que se est\u00e1n desarrollando en el cuartel de la Monta\u00f1a 4F en conmemoraci\u00f3n del segundo aniversario de la siembra eterna del comandante Supremo, Hugo Ch\u00e1vez.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La clase obrera que est\u00e1 en los medios de producci\u00f3n est\u00e1 llamada a asumir el control y producci\u00f3n en las empresas del pa\u00eds<\/p>\n","protected":false},"author":25,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[83],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST\" \/>\n<meta property=\"og:description\" content=\"La clase obrera que est\u00e1 en los medios de producci\u00f3n est\u00e1 llamada a asumir el control y producci\u00f3n en las empresas del pa\u00eds\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\" \/>\n<meta property=\"og:site_name\" content=\"MPPPST\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-11T19:20:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-01T14:45:28+00:00\" \/>\n<meta name=\"author\" content=\"MPPPST Prensa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"MPPPST Prensa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\"},\"author\":{\"name\":\"MPPPST Prensa\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\"},\"headline\":\"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds\",\"datePublished\":\"2015-03-11T19:20:37+00:00\",\"dateModified\":\"2016-07-01T14:45:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\"},\"wordCount\":474,\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"articleSection\":[\"Ministerio\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\",\"name\":\"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST\",\"isPartOf\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\"},\"datePublished\":\"2015-03-11T19:20:37+00:00\",\"dateModified\":\"2016-07-01T14:45:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"name\":\"MPPPST\",\"description\":\"Ministerio del Poder Popular para el Proceso Social de Trabajo\",\"publisher\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization\",\"name\":\"mpppst\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"contentUrl\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png\",\"width\":1080,\"height\":241,\"caption\":\"mpppst\"},\"image\":{\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4\",\"name\":\"MPPPST Prensa\",\"url\":\"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/","og_locale":"es_ES","og_type":"article","og_title":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST","og_description":"La clase obrera que est\u00e1 en los medios de producci\u00f3n est\u00e1 llamada a asumir el control y producci\u00f3n en las empresas del pa\u00eds","og_url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/","og_site_name":"MPPPST","article_published_time":"2015-03-11T19:20:37+00:00","article_modified_time":"2016-07-01T14:45:28+00:00","author":"MPPPST Prensa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"MPPPST Prensa","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#article","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/"},"author":{"name":"MPPPST Prensa","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4"},"headline":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds","datePublished":"2015-03-11T19:20:37+00:00","dateModified":"2016-07-01T14:45:28+00:00","mainEntityOfPage":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/"},"wordCount":474,"publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"articleSection":["Ministerio"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/","name":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds - MPPPST","isPartOf":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website"},"datePublished":"2015-03-11T19:20:37+00:00","dateModified":"2016-07-01T14:45:28+00:00","breadcrumb":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/2015\/03\/11\/la-clase-obrera-esta-llamada-a-asumir-el-control-y-produccion-de-las-empresas-en-el-pais\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/"},{"@type":"ListItem","position":2,"name":"La clase obrera est\u00e1 llamada a asumir el control y producci\u00f3n de las empresas en el pa\u00eds"}]},{"@type":"WebSite","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#website","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","name":"MPPPST","description":"Ministerio del Poder Popular para el Proceso Social de Trabajo","publisher":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#organization","name":"mpppst","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","contentUrl":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/wp-content\/uploads\/2025\/07\/cropped-cropped-g910.png","width":1080,"height":241,"caption":"mpppst"},"image":{"@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/#\/schema\/person\/fc187ee8ead412bd4c9304b62f900ea4","name":"MPPPST Prensa","url":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/author\/prensa-mpppst\/"}]}},"_links":{"self":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/2602"}],"collection":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/comments?post=2602"}],"version-history":[{"count":1,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/2602\/revisions"}],"predecessor-version":[{"id":6756,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/posts\/2602\/revisions\/6756"}],"wp:attachment":[{"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/media?parent=2602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/categories?post=2602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.mpppst.gob.ve\/mpppstweb\/index.php\/wp-json\/wp\/v2\/tags?post=2602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}